{"id":1898,"date":"2022-11-16T13:06:04","date_gmt":"2022-11-16T11:06:04","guid":{"rendered":"https:\/\/skaar.media\/?page_id=1898"},"modified":"2023-05-10T13:55:06","modified_gmt":"2023-05-10T11:55:06","slug":"front","status":"publish","type":"page","link":"https:\/\/skaar.media\/en\/","title":{"rendered":"Front page"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_1962043902\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle\"  id=\"row-1439538430\">\n\n\n\t<div id=\"col-430550939\" class=\"col medium-6 small-12 large-6\"  data-animate=\"flipInY\">\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2409666335\" class=\"text\">\n\t\t\n\n<h1>Web Development &amp; Marketing<\/h1>\n\t\t\n<style>\n#text-2409666335 {\n  font-size: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1708229015\" class=\"text\">\n\t\t\n\n<p>If you need a new website, online store or more sales in your channels, we can help you<\/p>\n\t\t\n<style>\n#text-1708229015 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-614661889\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"ux-lottie-1297835455\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/skaar.media\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/83846-marketing.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-1297835455&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-1297835455 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1962043902 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 600px;\n  background-color: rgb(197, 182, 208);\n}\n#section_1962043902 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0em;margin-bottom:0em;max-width:100%;height:1px;background-color:rgba(4, 4, 4, 0.395);\"><\/div>\n\n\n\t<section class=\"section\" id=\"section_103031716\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-equal row-solid\"  id=\"row-98930986\">\n\n\n\t<div id=\"col-1395676014\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"ux-lottie-2678523571\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/skaar.media\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/email-marketing.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-2678523571&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-2678523571 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>Facebook &amp; Social Media<\/h3>\n<p>For most companies, Facebook is the largest and most important platform on which to be visible. Let us help you reach the right people who create value for you<\/p>\n<a href=\"https:\/\/skaar.media\/en\/facebook\/\" class=\"button secondary is-underline lowercase\"  >\n\t\t<span>Read more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\t<div id=\"gap-1394024341\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1394024341 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1852189459\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"ux-lottie-43376440\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/skaar.media\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/business-salesman.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-43376440&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-43376440 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>Website<\/h3>\n<p>The first impression of your company, the core of information and value creation. If you need a new website or just renovation of an existing site, we are the right people for you<\/p>\n<a href=\"https:\/\/skaar.media\/en\/we-create-unique-websites\/\" class=\"button secondary is-underline lowercase\"  >\n\t\t<span>Read more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1776174999\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"ux-lottie-3039805597\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/skaar.media\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/business-team.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-3039805597&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-3039805597 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3>Agency services<\/h3>\n<p>Is it tempting to just throw all responsibility for websites and marketing to someone else? We can take full or partial responsibility for your digital presence<\/p>\n<a href=\"https:\/\/skaar.media\/en\/contact-us\/\" class=\"button secondary is-underline lowercase\"  >\n\t\t<span>Contact<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\t<div id=\"gap-1888397541\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1888397541 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-862437145\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"ux-lottie-4129579667\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/skaar.media\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/growth-analysis.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-4129579667&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-4129579667 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<\/p>\n<h3>Optimizations &amp; Analyzes<\/h3>\n<p>Do you just need a little push in the right direction? Let us analyze social media, websites or advertisements and we will also give you specific tips for possible improvement<\/p>\n<a href=\"https:\/\/skaar.media\/en\/contact-us\/\" class=\"button secondary is-underline lowercase\"  >\n\t\t<span>Contact<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-98930986 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_103031716 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(246, 244, 248);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0em;margin-bottom:0em;max-width:100%;height:1px;background-color:rgba(4, 4, 4, 0.395);\"><\/div>\n\n\n\t<section class=\"section\" id=\"section_1957219898\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-732357082\">\n\n\n\t<div id=\"col-73050133\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Our Clients<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-equal\"  id=\"row-784444407\">\n\n\n\t<div id=\"col-155032865\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  \n    <div class=\"row large-columns-6 medium-columns-3 small-columns-3\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"166\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/12\/logo_transparent-e1668071829136-1024x566-1-300x166.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/12\/logo_transparent-e1668071829136-1024x566-1-300x166.png 300w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/12\/logo_transparent-e1668071829136-1024x566-1-500x276.png 500w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/12\/logo_transparent-e1668071829136-1024x566-1-768x425.png 768w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/12\/logo_transparent-e1668071829136-1024x566-1.png 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Sterling Makeup<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"125\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/odeon-logo.png\" class=\"attachment-medium size-medium\" alt=\"Odeon Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/odeon-logo.png 250w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/odeon-logo-247x125.png 247w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Odeon Stavanger<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"125\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/fandrops-logo.png\" class=\"attachment-medium size-medium\" alt=\"Fandrops logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/fandrops-logo.png 250w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/fandrops-logo-247x125.png 247w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Fandrops<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"125\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/bsr-logo.png\" class=\"attachment-medium size-medium\" alt=\"BlueSky Residence Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/bsr-logo.png 250w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/bsr-logo-247x125.png 247w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>BlueSky Residence<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/04\/result.svg\" class=\"attachment-medium size-medium\" alt=\"Sklls Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Sklls<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"125\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/frank-walton-logo.png\" class=\"attachment-medium size-medium\" alt=\"Frank Walton Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/frank-walton-logo.png 250w, https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/frank-walton-logo-247x125.png 247w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Frank Walton<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"122\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/top-black.png\" class=\"attachment-medium size-medium\" alt=\"pro kost logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/top-black.png 250w, https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/top-black-247x122.png 247w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Pro-Kost<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/odel-og-eie.svg\" class=\"attachment-medium size-medium\" alt=\"Odel &amp; Eie Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"114\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/my-fam-logo-300x114.png\" class=\"attachment-medium size-medium\" alt=\"myfam logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" srcset=\"https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/my-fam-logo-300x114.png 300w, https:\/\/skaar.media\/wp-content\/uploads\/2021\/02\/my-fam-logo.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2023\/02\/smokkelenken-logo-full-wo-underline.svg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2023\/02\/TRANBERG_LOGO-01.svg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" style=\"width:65%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/skaar.media\/wp-content\/uploads\/2022\/11\/biago-logo-clean-1.svg\" class=\"attachment-medium size-medium\" alt=\"Biagio Logo\" ids=\"2147,1855,1857,1860,1725,1853,495,494,513,2709,2711,1815\" style=\"none\" lightbox=\"false\" columns=\"6\" columns__sm=\"3\" columns__md=\"3\" image_width=\"65\" title=\"\">                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-155032865 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-784444407 > .col > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1957219898 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"content-type":"","footnotes":""},"class_list":["post-1898","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/pages\/1898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/comments?post=1898"}],"version-history":[{"count":10,"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/pages\/1898\/revisions"}],"predecessor-version":[{"id":3221,"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/pages\/1898\/revisions\/3221"}],"wp:attachment":[{"href":"https:\/\/skaar.media\/en\/wp-json\/wp\/v2\/media?parent=1898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}